{"id":1389,"date":"2017-03-23T11:55:09","date_gmt":"2017-03-23T10:55:09","guid":{"rendered":"https:\/\/www.capitecorpus.com\/blog\/?p=1389"},"modified":"2025-03-12T11:55:36","modified_gmt":"2025-03-12T10:55:36","slug":"rhetorique-art-eloquence-discours","status":"publish","type":"post","link":"https:\/\/www.capitecorpus.com\/blog\/rhetorique-art-eloquence-discours\/","title":{"rendered":"La rh\u00e9torique, ou l&rsquo;art de l&rsquo;\u00e9loquence \u00e0 utiliser subtilement dans son discours&#8230;"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0La rh\u00e9torique\u00a0\u00bb \u2026 un concept qui date des temps anciens mais dont les prouesses syntaxiques fonctionnent toujours aujourd\u2019hui dans l\u2019art d\u2019argumenter. V\u00e9ritable outil dans un processus de conviction d\u2019autrui, la rh\u00e9torique permet de transformer un argument faible en argument fort gr\u00e2ce aux mots et \u00e0 leur construction.<\/p>\n<p style=\"text-align: justify;\">Un des plus c\u00e9l\u00e8bres rh\u00e9teurs, le Grec Protagoras (486-410 av. J.-C.), posa le principe dialectique selon lequel n\u2019importe quel sujet pouvait \u00eatre \u00e9nonc\u00e9 selon deux th\u00e8ses contraires. L\u2019importance r\u00e9sidant dans le fait qu\u2019elles \u00e9taient vraisemblables, donc que tout bon orateur pouvait faire passer n\u2019importe quelle id\u00e9e comme un fait av\u00e9r\u00e9. Prudence donc \u00e0 ne pas basculer dans l\u2019art de manipuler\u00a0! Utilis\u00e9e \u00e0 bon escient, la rh\u00e9torique permet simplement de structurer un discours percutant. En voici les figures de style principales\u00a0:<\/p>\n<h2 style=\"text-align: justify;\">Le passage du rationnel \u00e0 la constatation : la d\u00e9duction<\/h2>\n<p style=\"text-align: justify;\">La d\u00e9duction consiste \u00e0 partir de faits que votre interlocuteur tient pour acquis et \u00e0 l\u2019amener \u00e0 un autre fait qui en d\u00e9coule et que l\u2019on souhaite faire constater. Le raisonnement ne se r\u00e9alise pas par une observation directe des faits mais par la r\u00e9f\u00e9rence d\u2019une v\u00e9rit\u00e9 \u00e0 une autre, en partant d\u2019un fait au pr\u00e9alable accept\u00e9 par la personne en face de vous. Cette m\u00e9canique part d\u2019une affirmation g\u00e9n\u00e9rale pour aller vers une constatation particuli\u00e8re.<\/p>\n<p style=\"text-align: justify;\"><em><u>Exemple\u00a0: <\/u><\/em><\/p>\n<p style=\"text-align: justify;\">Fait av\u00e9r\u00e9\u00a0: le pr\u00e9sident de la R\u00e9publique est un homme.<\/p>\n<p style=\"text-align: justify;\">V\u00e9rit\u00e9 g\u00e9n\u00e9rale\u00a0: tous les hommes dorment.<\/p>\n<p style=\"text-align: justify;\">D\u00e9duction\u00a0: DONC, le pr\u00e9sident de la R\u00e9publique dort.<\/p>\n<h2 style=\"text-align: justify;\">Le passage de proposition \u00e0 une conclusion : le syllogisme<\/h2>\n<p style=\"text-align: justify;\">Le principe du syllogisme a \u00e9t\u00e9 mis en lumi\u00e8re par Aristote\u00a0! Il d\u00e9signe un raisonnement logique constitu\u00e9 de deux propositions qui am\u00e8nent vers une conclusion irr\u00e9futable. La diff\u00e9rence avec la d\u00e9duction \u00e9tant que le syllogisme s\u2019\u00e9tablit \u00e0 partir d\u2019hypoth\u00e8ses alors que la d\u00e9duction se construit \u00e0 partir de constatations.<\/p>\n<p style=\"text-align: justify;\">Il se construit en 3 \u00e9tapes\u00a0:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Enoncer une r\u00e8gle g\u00e9n\u00e9rale<\/li>\n<li>Revenir au cas particulier de son interlocuteur<\/li>\n<li>Faire le lien entre la r\u00e8gle g\u00e9n\u00e9rale et le lien particulier et arriver au r\u00e9sultat de votre d\u00e9monstration.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><u>Exemple\u00a0<\/u><\/em>:<\/p>\n<p style=\"text-align: justify;\">Un vendeur de produits financiers doit convaincre un particulier de souscrire \u00e0 un produit de retraite compl\u00e9mentaire :<\/p>\n<p style=\"text-align: justify;\">Hypoth\u00e8se 1\u00a0: tout le monde sait que le financement des retraites sera de plus en plus difficile.<\/p>\n<p style=\"text-align: justify;\">Hypoth\u00e8se 2\u00a0: vous souhaitez ne jamais \u00eatre \u00e0 la charge de vos enfants, et pouvoir conserver une ind\u00e9pendance financi\u00e8re.<\/p>\n<p style=\"text-align: justify;\">Syllogisme\u00a0: vous devez donc penser d\u00e8s \u00e0 pr\u00e9sent \u00e0 vous constituer une retraite compl\u00e9mentaire.<\/p>\n<p style=\"text-align: justify;\">Le syllogisme est une figure qui permet donc de donner beaucoup de poids \u00e0 votre discours.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Il permet de <span style=\"color: #ff9849;\"><strong>rationaliser une d\u00e9cision<\/strong>.<\/span> Le raisonnement structur\u00e9 que propose le syllogisme permet au cart\u00e9sien de trouver les justifications utiles pour se convaincre lui-m\u00eame de la pertinence de son choix.<\/li>\n<li>Il permet d\u2019exprimer <span style=\"color: #ff9849;\"><strong>une certaine rigueur<\/strong>.<\/span> Cette technique s\u2019appuie sur la force de l\u2019autorit\u00e9 et de la comp\u00e9tence de celui qui l\u2019\u00e9nonce. Il t\u00e9moigne d\u2019une ma\u00eetrise du sujet.<\/li>\n<li>Il permet de \u00ab <span style=\"color: #ff9849;\"><strong>vendre des crit\u00e8res de choix<\/strong><\/span> \u00bb. Il s\u2019agit sans doute ici de sa meilleure utilisation possible. Il est en effet n\u00e9cessaire que votre interlocuteur adh\u00e8re \u00e0 certains principes pour pouvoir ensuite accepter votre proposition. Le syllogisme sera tr\u00e8s utile pour appuyer l\u2019<span style=\"color: #ff9849;\"><strong>argumentation <\/strong><\/span>sur des crit\u00e8res de choix interm\u00e9diaires.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">L&rsquo;hypostatisation (ou l&rsquo;absence d&rsquo;index de r\u00e9f\u00e9rence)<\/h2>\n<p style=\"text-align: justify;\">Derri\u00e8re ce nom compliqu\u00e9 se cache la l\u00e9gitimation d\u2019une id\u00e9e par une donn\u00e9e conceptuelle. L\u2019argument s\u2019appuie alors sur une <span style=\"color: #ff9849;\"><strong>abstraction <\/strong><\/span>totale qui est trop <span style=\"color: #ff9849;\"><strong>subjective <\/strong><\/span>pour \u00eatre discut\u00e9e comme telle.<\/p>\n<p style=\"text-align: justify;\"><em><u>Exemple\u00a0:<\/u><\/em><\/p>\n<p style=\"text-align: justify;\">Selon la philosophie \u2026<\/p>\n<p style=\"text-align: justify;\">Le droit nous commande de \u2026<\/p>\n<p style=\"text-align: justify;\">Un bon orateur ne doit pas abuser de cette figure de style sous peine de parler dans le vide. Il l\u2019utilisera uniquement pour donner de la <span style=\"color: #ff9849;\"><strong>hauteur <\/strong><\/span>et une <span style=\"color: #ff9849;\"><strong>dimension philosophique <\/strong><\/span>\u00e0 son raisonnement.<\/p>\n<h2 style=\"text-align: justify;\">Le sublime<\/h2>\n<p style=\"text-align: justify;\">Si vous devez faire un discours qui emporte votre auditoire, la figure du sublime a pour objectif de cr\u00e9er <span style=\"color: #ff9849;\"><strong>un transport \u00e9motionnel collectif<\/strong><\/span>. Elle passe par un partage absolu d\u2019une \u00e9motion, comme un chanteur en transe devant son public sur sc\u00e8ne. Il s\u2019agit bien s\u00fbr d\u2019\u00eatre profond\u00e9ment convaincu de son propos et de son int\u00e9r\u00eat pour ses interlocuteurs pour esp\u00e9rer l\u2019atteindre. Quatre crit\u00e8res doivent \u00eatre r\u00e9unis pour cr\u00e9er une r\u00e9ception passionnelle de votre discours par votre auditoire\u00a0:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Une imagination fertile<\/li>\n<li>Une utilisation cons\u00e9quente des images et des m\u00e9taphores<\/li>\n<li>Un choix judicieux des mots et une excellente \u00e9loquence<\/li>\n<li>Un bon agencement de ceux-ci afin de cr\u00e9er une v\u00e9ritable m\u00e9lodie verbale<\/li>\n<\/ul>\n<div style=\"border: 2px solid #ff9849; padding: 15px; text-align: justify;\">\n<h3 style=\"letter-spacing: -0.01em; text-align: justify;\">Les\u00a0b\u00e9n\u00e9fices\u00a0d&rsquo;une bonne utilisation des figures de style de la rh\u00e9torique<\/h3>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\">Faire comprendre parfaitement votre message<\/li>\n<li style=\"text-align: justify;\">Faire adh\u00e9rer votre auditoire \u00e0 votre propos<\/li>\n<li style=\"text-align: justify;\">Faire aimer ce que vous voulez transmettre et ainsi motiver vos \u00e9quipes ou vos interlocuteurs !<\/li>\n<\/ul>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Pour aller plus loin :<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.capitecorpus.com\/formation-communication-soft-skills\/\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbD\u00e9couvrez nos formations en Communication orale\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb17px\u00a0\u00bb button_text_color=\u00a0\u00bb#df0f02&Prime; button_font=\u00a0\u00bb|600|||||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.capitecorpus.com\/formations-relation-client-efficacite-commerciale\/formation-techniques-influence\/\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbD\u00e9couvrez notre formation Commerciaux : augmenter son pouvoir d&rsquo;influence\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb17px\u00a0\u00bb button_text_color=\u00a0\u00bb#edb648&Prime; button_font=\u00a0\u00bb|600|||||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0La rh\u00e9torique\u00a0\u00bb \u2026 un concept qui date des temps anciens mais dont les prouesses syntaxiques fonctionnent toujours aujourd\u2019hui dans l\u2019art d\u2019argumenter. V\u00e9ritable outil dans un processus de conviction d\u2019autrui, la rh\u00e9torique permet de transformer un argument faible en argument fort gr\u00e2ce aux mots et \u00e0 leur construction. Un des plus c\u00e9l\u00e8bres rh\u00e9teurs, le Grec Protagoras [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: justify;\">\u00ab\u00a0La rh\u00e9torique\u00a0\u00bb \u2026 un concept qui date des temps anciens mais dont les prouesses syntaxiques fonctionnent toujours aujourd\u2019hui dans l\u2019art d\u2019argumenter. V\u00e9ritable outil dans un processus de conviction d\u2019autrui, la rh\u00e9torique permet de transformer un argument faible en argument fort gr\u00e2ce aux mots et \u00e0 leur construction.<\/p>\r\n<p style=\"text-align: justify;\">Un des plus c\u00e9l\u00e8bres rh\u00e9teurs, le Grec Protagoras (486-410 av. J.-C.), posa le principe dialectique selon lequel n\u2019importe quel sujet pouvait \u00eatre \u00e9nonc\u00e9 selon deux th\u00e8ses contraires. L\u2019importance r\u00e9sidant dans le fait qu\u2019elles \u00e9taient vraisemblables, donc que tout bon orateur pouvait faire passer n\u2019importe quelle id\u00e9e comme un fait av\u00e9r\u00e9. Prudence donc \u00e0 ne pas basculer dans l\u2019art de manipuler\u00a0! Utilis\u00e9e \u00e0 bon escient, la rh\u00e9torique permet simplement de structurer un discours percutant. En voici les figures de style principales\u00a0:<\/p>\r\n\r\n<h2 style=\"text-align: justify;\">Le passage du rationnel \u00e0 la constatation : la d\u00e9duction<\/h2>\r\n<p style=\"text-align: justify;\">La d\u00e9duction consiste \u00e0 partir de faits que votre interlocuteur tient pour acquis et \u00e0 l\u2019amener \u00e0 un autre fait qui en d\u00e9coule et que l\u2019on souhaite faire constater. Le raisonnement ne se r\u00e9alise pas par une observation directe des faits mais par la r\u00e9f\u00e9rence d\u2019une v\u00e9rit\u00e9 \u00e0 une autre, en partant d\u2019un fait au pr\u00e9alable accept\u00e9 par la personne en face de vous. Cette m\u00e9canique part d\u2019une affirmation g\u00e9n\u00e9rale pour aller vers une constatation particuli\u00e8re.<\/p>\r\n<p style=\"text-align: justify;\"><em><u>Exemple\u00a0: <\/u><\/em><\/p>\r\n<p style=\"text-align: justify;\">Fait av\u00e9r\u00e9\u00a0: le pr\u00e9sident de la R\u00e9publique est un homme.<\/p>\r\n<p style=\"text-align: justify;\">V\u00e9rit\u00e9 g\u00e9n\u00e9rale\u00a0: tous les hommes dorment.<\/p>\r\n<p style=\"text-align: justify;\">D\u00e9duction\u00a0: DONC, le pr\u00e9sident de la R\u00e9publique dort.<\/p>\r\n\r\n<h2 style=\"text-align: justify;\">Le passage de proposition \u00e0 une conclusion : le syllogisme<\/h2>\r\n<p style=\"text-align: justify;\">Le principe du syllogisme a \u00e9t\u00e9 mis en lumi\u00e8re par Aristote\u00a0! Il d\u00e9signe un raisonnement logique constitu\u00e9 de deux propositions qui am\u00e8nent vers une conclusion irr\u00e9futable. La diff\u00e9rence avec la d\u00e9duction \u00e9tant que le syllogisme s\u2019\u00e9tablit \u00e0 partir d\u2019hypoth\u00e8ses alors que la d\u00e9duction se construit \u00e0 partir de constatations.<\/p>\r\n<p style=\"text-align: justify;\">Il se construit en 3 \u00e9tapes\u00a0:<\/p>\r\n\r\n<ul style=\"text-align: justify;\">\r\n \t<li>Enoncer une r\u00e8gle g\u00e9n\u00e9rale<\/li>\r\n \t<li>Revenir au cas particulier de son interlocuteur<\/li>\r\n \t<li>Faire le lien entre la r\u00e8gle g\u00e9n\u00e9rale et le lien particulier et arriver au r\u00e9sultat de votre d\u00e9monstration.<\/li>\r\n<\/ul>\r\n<p style=\"text-align: justify;\"><em><u>Exemple\u00a0<\/u><\/em>:<\/p>\r\n<p style=\"text-align: justify;\">Un vendeur de produits financiers doit convaincre un particulier de souscrire \u00e0 un produit de retraite compl\u00e9mentaire :<\/p>\r\n<p style=\"text-align: justify;\">Hypoth\u00e8se 1\u00a0: tout le monde sait que le financement des retraites sera de plus en plus difficile.<\/p>\r\n<p style=\"text-align: justify;\">Hypoth\u00e8se 2\u00a0: vous souhaitez ne jamais \u00eatre \u00e0 la charge de vos enfants, et pouvoir conserver une ind\u00e9pendance financi\u00e8re.<\/p>\r\n<p style=\"text-align: justify;\">Syllogisme\u00a0: vous devez donc penser d\u00e8s \u00e0 pr\u00e9sent \u00e0 vous constituer une retraite compl\u00e9mentaire.<\/p>\r\n<p style=\"text-align: justify;\">Le syllogisme est une figure qui permet donc de donner beaucoup de poids \u00e0 votre discours.<\/p>\r\n\r\n<ul style=\"text-align: justify;\">\r\n \t<li>Il permet de <span style=\"color: #ff9849;\"><strong>rationaliser une d\u00e9cision<\/strong>.<\/span> Le raisonnement structur\u00e9 que propose le syllogisme permet au cart\u00e9sien de trouver les justifications utiles pour se convaincre lui-m\u00eame de la pertinence de son choix.<\/li>\r\n \t<li>Il permet d\u2019exprimer <span style=\"color: #ff9849;\"><strong>une certaine rigueur<\/strong>.<\/span> Cette technique s\u2019appuie sur la force de l\u2019autorit\u00e9 et de la comp\u00e9tence de celui qui l\u2019\u00e9nonce. Il t\u00e9moigne d\u2019une ma\u00eetrise du sujet.<\/li>\r\n \t<li>Il permet de \u00ab <span style=\"color: #ff9849;\"><strong>vendre des crit\u00e8res de choix<\/strong><\/span> \u00bb. Il s\u2019agit sans doute ici de sa meilleure utilisation possible. Il est en effet n\u00e9cessaire que votre interlocuteur adh\u00e8re \u00e0 certains principes pour pouvoir ensuite accepter votre proposition. Le syllogisme sera tr\u00e8s utile pour appuyer l\u2019<span style=\"color: #ff9849;\"><strong>argumentation <\/strong><\/span>sur des crit\u00e8res de choix interm\u00e9diaires.<\/li>\r\n<\/ul>\r\n<h2 style=\"text-align: justify;\">L'hypostatisation (ou l'absence d'index de r\u00e9f\u00e9rence)<\/h2>\r\n<p style=\"text-align: justify;\">Derri\u00e8re ce nom compliqu\u00e9 se cache la l\u00e9gitimation d\u2019une id\u00e9e par une donn\u00e9e conceptuelle. L\u2019argument s\u2019appuie alors sur une <span style=\"color: #ff9849;\"><strong>abstraction <\/strong><\/span>totale qui est trop <span style=\"color: #ff9849;\"><strong>subjective <\/strong><\/span>pour \u00eatre discut\u00e9e comme telle.<\/p>\r\n<p style=\"text-align: justify;\"><em><u>Exemple\u00a0:<\/u><\/em><\/p>\r\n<p style=\"text-align: justify;\">Selon la philosophie \u2026<\/p>\r\n<p style=\"text-align: justify;\">Le droit nous commande de \u2026<\/p>\r\n<p style=\"text-align: justify;\">Un bon orateur ne doit pas abuser de cette figure de style sous peine de parler dans le vide. Il l\u2019utilisera uniquement pour donner de la <span style=\"color: #ff9849;\"><strong>hauteur <\/strong><\/span>et une <span style=\"color: #ff9849;\"><strong>dimension philosophique <\/strong><\/span>\u00e0 son raisonnement.<\/p>\r\n\r\n<h2 style=\"text-align: justify;\">Le sublime<\/h2>\r\n<p style=\"text-align: justify;\">Si vous devez faire un discours qui emporte votre auditoire, la figure du sublime a pour objectif de cr\u00e9er <span style=\"color: #ff9849;\"><strong>un transport \u00e9motionnel collectif<\/strong><\/span>. Elle passe par un partage absolu d\u2019une \u00e9motion, comme un chanteur en transe devant son public sur sc\u00e8ne. Il s\u2019agit bien s\u00fbr d\u2019\u00eatre profond\u00e9ment convaincu de son propos et de son int\u00e9r\u00eat pour ses interlocuteurs pour esp\u00e9rer l\u2019atteindre. Quatre crit\u00e8res doivent \u00eatre r\u00e9unis pour cr\u00e9er une r\u00e9ception passionnelle de votre discours par votre auditoire\u00a0:<\/p>\r\n\r\n<ul style=\"text-align: justify;\">\r\n \t<li>Une imagination fertile<\/li>\r\n \t<li>Une utilisation cons\u00e9quente des images et des m\u00e9taphores<\/li>\r\n \t<li>Un choix judicieux des mots et une excellente \u00e9loquence<\/li>\r\n \t<li>Un bon agencement de ceux-ci afin de cr\u00e9er une v\u00e9ritable m\u00e9lodie verbale<\/li>\r\n<\/ul>\r\n<div style=\"border: 2px solid #ff9849; padding: 15px; text-align: justify;\">\r\n<h3 style=\"letter-spacing: -0.01em; text-align: justify;\">Les\u00a0b\u00e9n\u00e9fices\u00a0d'une bonne utilisation des figures de style de la rh\u00e9torique<\/h3>\r\n<ul style=\"text-align: justify;\">\r\n \t<li style=\"text-align: justify;\">Faire comprendre parfaitement votre message<\/li>\r\n \t<li style=\"text-align: justify;\">Faire adh\u00e9rer votre auditoire \u00e0 votre propos<\/li>\r\n \t<li style=\"text-align: justify;\">Faire aimer ce que vous voulez transmettre et ainsi motiver vos \u00e9quipes ou vos interlocuteurs !<\/li>\r\n<\/ul>\r\n<\/div>\r\n&nbsp;\r\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.capitecorpus.com\/blog\/communication-orale\"><img class=\"alignnone size-full wp-image-1102\" src=\"https:\/\/www.capitecorpus.com\/blog\/wp-content\/uploads\/2016\/05\/bouton-cta-communication-orale-gros.png\" alt=\"Formations communication orale\" width=\"554\" height=\"46\" \/><\/a><\/p>\r\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.capitecorpus.com\/formation-commerciale\/formation-techniques-influence\">Commerciaux : augmenter votre pouvoir d'influence<\/a><\/p>","_et_gb_content_width":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-1389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boite-a-outils","et-has-post-format-content","et_post_format-et-post-format-standard"],"views":3507,"_links":{"self":[{"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/posts\/1389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/comments?post=1389"}],"version-history":[{"count":4,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/posts\/1389\/revisions"}],"predecessor-version":[{"id":3992,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/posts\/1389\/revisions\/3992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/media\/3987"}],"wp:attachment":[{"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/media?parent=1389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/categories?post=1389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.capitecorpus.com\/blog\/wp-json\/wp\/v2\/tags?post=1389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}